{"id":206086,"date":"2026-02-15T21:06:27","date_gmt":"2026-02-15T20:06:27","guid":{"rendered":"https:\/\/www.tierslivre.net\/ateliers\/?p=206086"},"modified":"2026-02-16T08:42:00","modified_gmt":"2026-02-16T07:42:00","slug":"construire-05-voir","status":"publish","type":"post","link":"https:\/\/www.tierslivre.net\/ateliers\/construire-05-voir\/","title":{"rendered":"#construire #05 | Voir"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br>Voir se dessiner le trajet de la premi\u00e8re note, toujours une surprise bien qu\u2019on l\u2019attende avec crainte \u00e0 chaque moment du jour ou de la nuit, douce avant une lente mont\u00e9e vers les aigus. Elle s\u2019amplifie pour se stabiliser en un hurlement qui sature tout l\u2019air, emp\u00eache de respirer. Inoffensive sir\u00e8ne. Voir la peur envahir le corps dans la nuit. Toutes lumi\u00e8res \u00e9teintes en camouflage d\u00e9risoire rien ne peut plus d\u00e9vier la trajectoire juste la chance. Voir les pieds nus courir vers la porte au fond de la cuisine. Les pieds nus petits l\u2019un devant l\u2019autre h\u00e9sitants se cogner pr\u00e9cipit\u00e9s sur le pied de la table heurter le banc d\u2019un genou toucher terre se redresser pieds nus l\u2019un apr\u00e8s l\u2019autre sur les chevilles fines si fragiles. Courir vers la porte. Arr\u00eat sur un trou noir pas possible d\u2019\u00e9couter la peur. Voir se dessiner les premi\u00e8res marches d\u2019un escalier. Les pied petits un pas apr\u00e8s l\u2019autre nus sur le b\u00e9ton glac\u00e9 des marches leur trace dans la poussi\u00e8re jusqu\u2019en bas, jusqu\u2019\u00e0 la grande caisse dans le noir. Voir entre les planches disjointes de la caisse de bois, refuge presque am\u00e9nag\u00e9, les boucles d\u00e9passer sous la couverture secou\u00e9e de tremblement, les deux mains plaqu\u00e9es sur les oreilles. La sir\u00e8ne s\u2019est tue, silence avant le vacarme. Voir s\u2018\u00e9couler la nuit la t\u00eate enfouie au plus profond de la couverture, les mains \u00e9crasent le tissu sur les oreilles. Attendre. Compter. Craindre. Voir dans la caisse le corps sursauter quand l\u2019explosion se produit, enfin. Sc\u00e9nario d\u00e9j\u00e0 \u00e9crit aucune r\u00e9p\u00e9tition ne permet de s\u2019habituer \u00e0 la terreur. Voir le bruit traverser les mains pour percer les tympans. Voir la lumi\u00e8re de l\u2019aube tombant du soupirail \u00e9clairer la trace des pieds dans la poudre de charbon qui couvre le sol. Nuage de d\u00e9bris, la sir\u00e8ne de fin d\u2019alerte s\u2019est tue. Voir entre les d\u00e9combres, le reste d\u2019une table, les morceaux d\u2019une assiette, une bo\u00eete en fer blanc qui contient des \u0153ufs intacts, un sac de farine \u00e9ventr\u00e9. Voir que les cheveux ont blanchi en  une nuit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voir se dessiner le trajet de la premi\u00e8re note, toujours une surprise bien qu\u2019on l\u2019attende avec crainte \u00e0 chaque moment du jour ou de la nuit, douce avant une lente mont\u00e9e vers les aigus. Elle s\u2019amplifie pour se stabiliser en un hurlement qui sature tout l\u2019air, emp\u00eache de respirer. Inoffensive sir\u00e8ne. Voir la peur envahir le corps dans la nuit. <a class=\"more-link\" href=\"https:\/\/www.tierslivre.net\/ateliers\/construire-05-voir\/\">Continuer la lecture<span class=\"screen-reader-text\">#construire #05 | Voir<\/span><span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":284,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"footnotes":""},"categories":[7934,7971,1],"tags":[],"class_list":["post-206086","post","type-post","status-publish","format-standard","hentry","category-construire-nouveau-cycle-2026","category-05-collobert-loeil-interieur","category-atelier"],"_links":{"self":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts\/206086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/users\/284"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/comments?post=206086"}],"version-history":[{"count":3,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts\/206086\/revisions"}],"predecessor-version":[{"id":206095,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts\/206086\/revisions\/206095"}],"wp:attachment":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/media?parent=206086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/categories?post=206086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/tags?post=206086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}