{"id":208059,"date":"2026-04-12T16:02:16","date_gmt":"2026-04-12T14:02:16","guid":{"rendered":"https:\/\/www.tierslivre.net\/ateliers\/?p=208059"},"modified":"2026-04-14T17:40:50","modified_gmt":"2026-04-14T15:40:50","slug":"construire-11-traversees","status":"publish","type":"post","link":"https:\/\/www.tierslivre.net\/ateliers\/construire-11-traversees\/","title":{"rendered":"#construire #11 |  La panne etc\u00e9t\u00e9ra"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il \u00e9volue dans une atmosph\u00e8re charg\u00e9e d\u2019obscurit\u00e9, d&rsquo;un noir bleu intense, les vitrines \u00e9teintes des magasins ne renvoient aucune image, aucun reflet. Il est d\u00e9sorient\u00e9, livr\u00e9 au hasard. Une rue vide, un endroit o\u00f9 il n\u2019aurait jamais d\u00fb \u00eatre, o\u00f9 il n\u2019aurait jamais d\u00fb \u00e9crire, o\u00f9 il n\u2019aurait jamais d\u00fb vivre cet auto exil. Il ne sait pas o\u00f9 il rencontrera son style, ses mots, son genre, ses si\u00e8cles, la pudeur de son langage? Il marche pour poss\u00e9der une id\u00e9e, une \u00e9tincelle de justesse, des soup\u00e7ons d\u2019imaginaire. Il cherche le lieu o\u00f9 se noue le lien entre l\u2019homme et le langage, l\u2019oral qui pourrait constituer l\u2019\u00e9crit. Il voudrait \u00eatre pr\u00e9tentieux pour penser \u00e9crire un langage second, mais rien. La barre est trop haute. Enferm\u00e9 dans cet espace clos d\u00e9limit\u00e9 par des rues perpendiculaires, des trottoirs, des plans, des constructions disparates, il \u00e9lague, rature, reprend, et tout \u00e0 coup, pris d&rsquo;une soudaine fr\u00e9n\u00e9sie il jette ses cahiers remplis d&rsquo;une \u00e9criture absente, des piles de notes, des fiches, toutes ses failles, tout son travail remis en question pour accoucher d\u2019une phrase. Une seule r\u00e9ponse. <em>Faut-il d\u00e9truire ce que l\u2019on a \u00e9crit et recommencer pour se plonger dans la v\u00e9ritable \u00e9criture, celle qu\u2019un \u00e9crivain cherche<\/em>?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il avance pour trouver ses rythmes, plans, attitudes, harmonies, musiques, danses, amulettes, d\u00e9passer ses pannes, visualiser sa renaissance, sa jouissance m\u00eame \u00e9ph\u00e9m\u00e8re, poursuivre son r\u00eave, son fantasme, son \u00e9bauche de quelque chose encore innom\u00e9e. Il devine la forme floue d\u2019un v\u00e9hicule, la perception vague dune voiture de forme cubique en panne gar\u00e9e de biais, moiti\u00e9 sur le trottoir, moiti\u00e9 sur la route, phares \u00e9teints, comme un emp\u00eachement, un blocage, une difficult\u00e9, une contrainte, une g\u00eane, un obstacle, une impuissance, une impossibilit\u00e9 d\u2019\u00e9crire. La force d&rsquo;une id\u00e9e impr\u00e9cise lui barre la route, entrave ses mouvements, paralyse sa main. Tout se trouble. Aucun visage. Aucune silhouette. Il est seul face \u00e0 ses pannes \u00e0 d\u00e9faire, surmonter, franchir, \u00e0 d\u00e9manteler, d\u00e9passer par des strat\u00e9gies, des rituels, des lectures, relectures, \u00e9critures, r\u00e9\u00e9critures. Une attente. Un doute suspendu. Une courbe de perplexit\u00e9, l&rsquo;informe \u00e0 rationaliser. Un sacerdoce, une d\u00e9votion, un signe comme un appel. Au coin de la rue un tube lumineux s\u2019\u00e9teint \u00e0 son approche. La lumi\u00e8re se volatilise. Son regard s\u2019absente. Ses traces font dispara\u00eetre ses rep\u00e8res. Il franchit un passage vers une zone inconnue sans \u00e9clairage. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il transforme son manuscrit au prix d&rsquo;un sc\u00e9nario \u00e9trange, d&rsquo;une situation hallucin\u00e9e o\u00f9 il doit \u00e9crire des articles avec des consignes, contraintes, qu&rsquo;il ne reconnait pas. Id\u00e9e absurde. Ubuesque. Une voix suave r\u00e9sonne dans sa t\u00eate, lui donne des pistes de travail. Force, espoir, rythme, fiert\u00e9, haine sauvagerie, douceur, amour, peine, d\u00e9sespoir, m\u00ealer imaginer les styles, les cultures, les langues, d\u00e9chiffrer un code, mais un code pour d\u00e9chiffrer autre chose, d\u00e9passer les clich\u00e9s, provoquer d\u2019autres regards, livrer ses n\u00e9vroses, les \u00e9taler devant les autres, tous les autres, \u00eatre le sujet d\u2019un langage articul\u00e9. Faut-il n\u2019avoir aucune pudeur pour \u00e9crire avec soi? Il n\u2019y arrivera pas, incapable d\u2019affirmer sa pr\u00e9sence, il se cache et regarde en face ses manques, ses pannes d\u00e9routantes, ses d\u00e9faillances anticip\u00e9es pour affronter les jugements, critiques sarcastiques et pour finalement comprendre, saisir, que <em>ce qui se passe dans un r\u00e9el suppos\u00e9 est toujours irr\u00e9aliste.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il m\u00e9tamorphose son manuscrit d\u00e9construit &#8211; il le pr\u00e9sume illisible &#8211; laisse d\u00e9border son d\u00e9sordre, ses pannes en attente. Il veut le photocopier, le reproduire, le rendre pr\u00e9sentable, le diffuser m\u00eame incomplet, le faire lire, avoir des retours, dire le r\u00e9el de ses pannes trouver les moyens de les solutionner. Tout est ferm\u00e9, il n\u2019y a pas une \u00e2me. Il part \u00e0 la recherche d\u2019un taxi dans cette nuit sans fin avec ses incoh\u00e9rences, ses absurdit\u00e9s, ses d\u00e9convenues, ses espoirs fl\u00e9tris, ses failles en vrac<strong>,<\/strong> ses non-sens, ses d\u00e9ceptions, ses doutes obsessionnels, ses pannes occult\u00e9es. Comment sortir de ce lieu l\u00e0 o\u00f9 il n&rsquo;est pas? Dans ce fragile espace psychique l\u2019obscurit\u00e9 est muette. Il redoute la travers\u00e9e de ce vide o\u00f9 il laisse tomber son manuscrit. Il est l\u00e0, dans ce moment, o\u00f9 rien ne peut plus se lire, o\u00f9 il ne veut plus \u00e9crire. Sa d\u00e9sorientation est radicale. Il porte en lui son travail ind\u00e9cis qui refuse l\u2019injonction. Il s&rsquo;immerge dans une structure qui s&#8217;embo\u00eete dans une autre structure puis encore une autre. Il n&rsquo;est pas dans une simple obscurit\u00e9 visuelle constitu\u00e9e de pannes \u00e0 r\u00e9soudre par des actions correctives, il est dans une substance au stade de transformation, de gestation, de transition. Il dessine la g\u00e9ographie int\u00e9rieure d&rsquo;un monde d&rsquo;o\u00f9 il n&rsquo;est pas. Il y laissera une partie de lui-m\u00eame. Il s&rsquo;en \u00e9vadera avec des pratiques combinatoires, le lieu clos, la s\u00e9rie, la structure, l\u2019image, l&rsquo;unit\u00e9 d\u2019imitation, des vues, des petits tableaux cadr\u00e9s, des correspondances.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il \u00e9volue dans une atmosph\u00e8re charg\u00e9e d\u2019obscurit\u00e9, d&rsquo;un noir bleu intense, les vitrines \u00e9teintes des magasins ne renvoient aucune image, aucun reflet. Il est d\u00e9sorient\u00e9, livr\u00e9 au hasard. Une rue vide, un endroit o\u00f9 il n\u2019aurait jamais d\u00fb \u00eatre, o\u00f9 il n\u2019aurait jamais d\u00fb \u00e9crire, o\u00f9 il n\u2019aurait jamais d\u00fb vivre cet auto exil. Il ne sait pas o\u00f9 il <a class=\"more-link\" href=\"https:\/\/www.tierslivre.net\/ateliers\/construire-11-traversees\/\">Continuer la lecture<span class=\"screen-reader-text\">#construire #11 |  La panne etc\u00e9t\u00e9ra<\/span><span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":700,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"footnotes":""},"categories":[7934,8011],"tags":[],"class_list":["post-208059","post","type-post","status-publish","format-standard","hentry","category-construire-nouveau-cycle-2026","category-construire-11-barthes-la-panne"],"_links":{"self":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts\/208059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/users\/700"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/comments?post=208059"}],"version-history":[{"count":3,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts\/208059\/revisions"}],"predecessor-version":[{"id":208128,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts\/208059\/revisions\/208128"}],"wp:attachment":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/media?parent=208059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/categories?post=208059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/tags?post=208059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}