{"id":215376,"date":"2026-07-15T09:27:51","date_gmt":"2026-07-15T07:27:51","guid":{"rendered":"https:\/\/www.tierslivre.net\/ateliers\/?p=215376"},"modified":"2026-07-15T09:47:12","modified_gmt":"2026-07-15T07:47:12","slug":"chronique-02","status":"publish","type":"post","link":"https:\/\/www.tierslivre.net\/ateliers\/chronique-02\/","title":{"rendered":"#chronique #02 | ressassis"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">1|<\/h2>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><em>Comment continuer sans poser une bombe ?<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le bon sens n\u2019est pas la chose la plus appr\u00e9ci\u00e9e dans le monde de l\u2019art. En l\u2019espace de quelques semaines, je vois deux \u00e9crivains enfoncer le m\u00eame clou, au grand d\u00e9plaisir de leur interlocuteur.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4| D\u00e9ceptions<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lors d\u2019une rencontre \u00e0 Valenciennes, Gr\u00e9goire Delacourt explique tranquillement que si ses romans se passent dans le Nord, ce n\u2019est pas par sentimentalisme, mais pour faire l\u2019\u00e9conomie de longues recherches.<br>Pour Mauvignier, dans <em>Le Monde<\/em>&nbsp;:<br><em>Quand je situe un livre dans un endroit que je connais, ce n\u2019est pas un d\u00e9cor mais l\u2019espace o\u00f9 l\u2019\u00e9criture se d\u00e9ploie. Je n\u2019ai besoin d\u2019aucune documentation parce que je sais comment les pavillons sont faits, les rues sont faites, les fermes sont faites.&nbsp;<\/em><br><em>Au XIIe si\u00e8cle, d\u00e9ception a le sens de \u00ab tromperie \u00bb. Emprunt\u00e9 du bas latin deceptio, \u00ab action de tromper, d&rsquo;\u00eatre tromp\u00e9 \u00bb. Au XXe, d\u00e9ception indique fait d&rsquo;\u00eatre d\u00e9\u00e7u ; d\u00e9sappointement.<\/em> CNRTL<br>La pr\u00e9cision de Gr\u00e9goire Delacourt quant \u00e0 sa motivation premi\u00e8re pour situer ses romans dans le Nord fut, pour l\u2019animatrice du club de lecture, <em>une am\u00e8re, une cuisante, une compl\u00e8te d\u00e9ception<\/em>.<br>L\u2019annonce par Mauvignier que Florent Cabanel n\u2019existait pas, fut pour Alain Finkielkraut <em>une cruelle d\u00e9ception.<\/em><br>On l\u2019aura compris (peut-\u00eatre), c\u2019est le lien entre la d\u00e9ception (tromperie) et la d\u00e9ception (d\u00e9sappointement) qui m\u2019int\u00e9resse. Ce que nous investissons (distillons, engouffrons) d\u2019imagination dans une tromperie (un trompe-l\u2019\u0153il, une substitution, un conte) est irr\u00e9cup\u00e9rable. Une fois le pot au rose d\u00e9voil\u00e9, quelque chose de nous reste \u00e0 y croire, parce que nous nous attachons tr\u00e8s vite aux id\u00e9es nouvelles (d\u00e9favorables ou non) qui nous traversent quand nous sommes ainsi stimul\u00e9s (conduits, d\u00e9pays\u00e9s). Un attachement similaire nous emp\u00eache de couper dans nos textes alors m\u00eame qu\u2019il appara\u00eet clairement \u00e0 la relecture, qu\u2019ils ne valent pas le d\u00e9tour. Le moment de cet errement (\u00e9garement, abandon), l\u2019endroit o\u00f9 il nous a men\u00e9, quand bien m\u00eame c\u2019est une impasse (un cul-de-sac, un site de carte postale d\u00e9voy\u00e9), nous le reconnaissons comme n\u00f4tre. Comme davantage n\u00f4tre que tout ce que nous avions cru poss\u00e9der ou \u00eatre.<br>En ce qui me concerne, \u00e9crire (conter, mettre en sc\u00e8ne, voire enseigner) va de d\u00e9ception en d\u00e9ception. La forme est par essence arrangement, tromperie, artifice. Le jeu de la forme est si puissant, que m\u00eame d\u00e9voil\u00e9, il continue d\u2019op\u00e9rer.<br>Apr\u00e8s un spectacle, je fais visiter les coulisses \u00e0 un groupe de m\u00e9c\u00e8nes. Ce qui les intrigue en particulier, c\u2019est la piscine du d\u00e9cor. Ou plut\u00f4t comment, compte tenu de budgets de l\u2019\u00e9cole, nous avons pu nous offrir un \u00e9l\u00e9ment sc\u00e9nographique aussi co\u00fbteux. Ils savent qu\u2019ils ne sont pas \u00e0 l\u2019op\u00e9ra de Paris et flairent l\u2019embrouille. Pourtant, ils tombent de haut quand je leur fais emprunter l\u2019\u00e9chelle m\u00e9tallique donnant acc\u00e8s aux dessous du th\u00e9\u00e2tre par une trappe ouverte. Une \u00e9chelle et un rebord ont suffi \u00e0 leur imagination pendant deux heures. Elle leur a fourni d\u2019innombrables pistes (souvenirs, sp\u00e9culations techniques, sensations\u2026). La r\u00e9alit\u00e9 les d\u00e9\u00e7oit. Elle est trop mince. Personne ne veut savoir que la r\u00e9alit\u00e9 n\u2019est compos\u00e9e que de ce que nous y apportons ni que l\u2019art consiste \u00e0 nous d\u00e9faire de ces apports pour en jouer \u00e0 sa guise. Guise qui d\u00e9passe de tr\u00e8s loin l\u2019ambition de l\u2019artiste.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5| La face aux ressassis<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Elle est en retard. Elle est toujours en retard quand c\u2019est possible. Or c\u2019est possible&nbsp;: nous sommes amies depuis si longtemps que nous n\u2019avons pas le souvenir de nous \u00eatre jamais rencontr\u00e9es. J\u2019\u00e9cris jusqu\u2019\u00e0 ce qu\u2019elle vienne. Un passage manquant (ou non) dans ce livre que je veux terminer. J\u2019\u00e9cris utile, j\u2019\u00e9cris en attendant, j\u2019\u00e9cris sur un mauvais cahier pour ce genre de texte de longue haleine. Il s\u2019ouvre mal et je manque d\u2019appui pour tracer des lettres correctes. C\u2019est d\u00e9sagr\u00e9able \u00e0 regarder et je sens que ce sera d\u00e9sagr\u00e9able \u00e0 relire. L\u2019agr\u00e9ment n\u2019est pas vraiment ce que je cherche. Par \u00ab&nbsp;d\u00e9sagr\u00e9able&nbsp;\u00bb, j\u2019entends cette nuance de m\u00e9pris et d\u2019agacement dans la voix de ma grand-m\u00e8re quand elle qualifiait quelqu\u2019un ainsi. Elle accentuait le \u2013 d\u00e9. Un casse-pied \u00e9tait une variante. Je pensais alors \u00e0 un danseur maladroit et je riais. Aujourd\u2019hui, j\u2019ai l\u2019\u00e2ge qu\u2019elle avait quand elle enrichissait mon vocabulaire de dizaines de mani\u00e8res diff\u00e9rentes d\u2019exprimer poliment l\u2019exasp\u00e9ration. Derri\u00e8re le mot presqu\u2019enfantin, je per\u00e7ois bien la force canalis\u00e9e du marteau sur tous les petits os. J\u2019h\u00e9site \u00e0 reprendre mes pattes de mouches, \u00e0 les saisir ici. Ce serait une bonne mani\u00e8re de les \u00e9craser. J\u2019\u00e9cris en attendant mon amie et je perds mon temps, j\u2019\u00e9gare le personnage, il se perd en consid\u00e9rations et perd ma consid\u00e9ration. Il est r\u00e9cemment devenu un type imbuvable, ce ne serait pas un probl\u00e8me, mais s\u2019il tourne aussi mal, c\u2019est que je n\u2019assume pas sa po\u00e9sie, celle qu\u2019il \u00e9crit et \u00e0 laquelle je consacre pourtant plusieurs pages dans le livre que veux terminer. J\u2019insiste inutilement. Je tarabiscote un moyen de mettre dans ses mains, comme par enchantement, <em>Couleurs et Peintures<\/em> de Coffignier. \u00c0 quoi bon&nbsp;? Encore un ch\u00e9ri \u00e0 tuer. Quand je pense que ce matin m\u00eame, j\u2019\u00e9tais visit\u00e9e par l\u2019intuition du <em>cut-up<\/em>, dans l\u2019\u00e9blouissement d\u2019un r\u00eave \u00e9veill\u00e9&nbsp;! Le bloc de savon blanc sur la fa\u00efence du lavabo ne s\u2019embarrassait pas&nbsp;: ton type est imbuvable, pourquoi se donnerait-il la peine d\u2019expliciter sa trajectoire. Un mot d\u2019introduction (je devrais dormir, mais je vous r\u00e9ponds), une note griffonn\u00e9e de son journal (<em>Dans une fabrique de couleurs, l\u2019atelier de pr\u00e9cipitation est celui qui occupe le plus grand emplacement<\/em>\/<em>Couleurs et Peintures<\/em>, Coffignier, bouquiniste angle Saint Maur et\u2026). C\u2019\u00e9tait clair, c\u2019\u00e9tait autrement que mes <em>ressassis<\/em> coutumiers. De ce courage, de cette franchise, il ne me reste que la face B. Je vois le chapeau de soleil de mon amie traverser la petite foule des baigneurs qui s\u2019\u00e9brouent et des belles alanguies au bord de l\u2019eau. Pour terminer le livre que je veux terminer, il va falloir terminer d&rsquo;abord celui que je ne veux plus \u00e9crire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand je pense que ce matin m\u00eame, j\u2019\u00e9tais visit\u00e9e par l\u2019intuition du cut-up, dans l\u2019\u00e9blouissement d\u2019un r\u00eave \u00e9veill\u00e9\u00a0!  <a class=\"more-link\" href=\"https:\/\/www.tierslivre.net\/ateliers\/chronique-02\/\">Continuer la lecture<span class=\"screen-reader-text\">#chronique #02 | ressassis<\/span><span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":43,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"footnotes":""},"categories":[8106,8147,1],"tags":[],"class_list":["post-215376","post","type-post","status-publish","format-standard","hentry","category-ete-2026-chroniques","category-ete-2026-02-semaine-2","category-atelier"],"_links":{"self":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts\/215376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/comments?post=215376"}],"version-history":[{"count":3,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts\/215376\/revisions"}],"predecessor-version":[{"id":215671,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts\/215376\/revisions\/215671"}],"wp:attachment":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/media?parent=215376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/categories?post=215376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/tags?post=215376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}