{"id":215549,"date":"2026-07-14T12:11:18","date_gmt":"2026-07-14T10:11:18","guid":{"rendered":"https:\/\/www.tierslivre.net\/ateliers\/?p=215549"},"modified":"2026-07-14T17:27:02","modified_gmt":"2026-07-14T15:27:02","slug":"ete-2026-02-voyages","status":"publish","type":"post","link":"https:\/\/www.tierslivre.net\/ateliers\/ete-2026-02-voyages\/","title":{"rendered":"#chroniques #02 | Voyages"},"content":{"rendered":"\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.tierslivre.net\/ateliers\/wp-content\/uploads\/2026\/07\/mes-chroniques-02-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 mes chroniques #02.\"><\/object><a id=\"wp-block-file--media-2ffd4394-f199-4860-ac10-8b1b8cfd3198\" href=\"https:\/\/www.tierslivre.net\/ateliers\/wp-content\/uploads\/2026\/07\/mes-chroniques-02-1.pdf\">mes chroniques #02<\/a><a href=\"https:\/\/www.tierslivre.net\/ateliers\/wp-content\/uploads\/2026\/07\/mes-chroniques-02-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-2ffd4394-f199-4860-ac10-8b1b8cfd3198\">T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1<\/strong> \u00ab&nbsp;<strong>Comment mourir sans <\/strong><strong>\u00ea<\/strong><strong>tre n<\/strong><strong>\u00e9&nbsp;<\/strong><strong>?<\/strong>&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2<\/strong> <strong>La chambre 12<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est dans un fauteuil roulant que je d\u00e9couvre la chambre 12 de la maison de sant\u00e9 dans laquelle je s\u00e9journerai plusieurs semaines pour ma convalescence et la r\u00e9\u00e9ducation de ma hanche droite. L\u2019aide-soignante ouvre la porte, me pousse en avant. D\u2019un regard circulaire, je d\u00e9couvre mon nouveau domaine&nbsp;: murs jaune, plafond blanc, sol bleu gris. En tournant mon regard vers la gauche, au milieu du panneau, le lit m\u00e9dicalis\u00e9 avec sa manette de r\u00e9glage des diff\u00e9rentes positions, sa potence, ses commandes pour l\u2019\u00e9clairage, sa sonnette. Au-dessus de lui des prises pour les appareils de surveillance du patient, en cas de besoin. \u00c0 gauche du lit, la table de nuit, avec un tiroir et une niche, pour mes livres et mon t\u00e9l\u00e9phone. Face \u00e0 moi, une grande baie vitr\u00e9e donnant sur un arbre, un platane dont la ramure de printemps toute neuve occupe presque tout l\u2019espace. Quel bonheur, cette verdure qui p\u00e9n\u00e8tre la chambre&nbsp;! Sous la fen\u00eatre, l\u00e9g\u00e8rement sur la gauche un fauteuil. Pas une berg\u00e8re Napol\u00e9on III \u2014 nous sommes dans un \u00e9tablissement de sant\u00e9&nbsp;\u2014 un fauteuil m\u00e9dical avec tout le fourbi adaptable pour le repos de la t\u00eate, du dos, des bras et des jambes, \u2014 en ska\u00ef vert le fauteuil, vert pomme. Contre le mur, une table \u00e0 roulettes, de celles qui peuvent \u00eatre install\u00e9es au-dessus d\u2019un lit pour les repas ou la lecture, \u00e9quip\u00e9e d\u2019une chaise dont l\u2019assise est du m\u00eame ska\u00ef que le fauteuil. Sur la table une carafe d\u2019eau et un verre. Sur le mur de droite, la porte de la salle bain avec d\u2019un c\u00f4t\u00e9 un placard dans lequel je rangerai mes v\u00eatements et ma paire de sneakers de rechange \u2014 mieux vaut pr\u00e9voir \u2014 et de l\u2019autre l\u2019\u00e9cran de t\u00e9l\u00e9vision. Au-dessus un climatiseur. C\u2019est lorsque que l\u2019aide-soignante m\u2019aura laiss\u00e9e seule, qu\u2019ayant fait pivoter mon fauteuil, je pourrai examiner le quatri\u00e8me mur, celui de la porte de la chambre sur laquelle sont affich\u00e9s le plan d\u2019\u00e9vacuation, les consignes de s\u00e9curit\u00e9 et quelques points du r\u00e8glement de la maison. \u00c0 droite de la porte un distributeur de gel d\u00e9sinfectant pour les mains. Quand j\u2019aurai mis un peu de mon d\u00e9sordre, je serai chez moi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3 <strong>\u00c9<\/strong><strong>clats de voyage<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Je n\u2019ai jamais \u00e9crit de roman de voyage et je n\u2019en \u00e9crirai pas. L\u2019id\u00e9e de prendre des notes et des photos pour, de retour \u00e0 ma table de travail, raconter un p\u00e9riple, m\u00eame en y mettant, un peu ou beaucoup de moi, me fatigue rien que d\u2019y penser. J\u2019ai cependant utilis\u00e9 des bribes de mes voyages, dans l\u2019un ou l\u2019autre de mes textes, pour d\u00e9crire un d\u00e9cor ou camper un personnage. Les rassembler dans un recueil pourrait \u00eatre int\u00e9ressant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;<\/strong><strong>Bribe 1<\/strong>&nbsp;<em>Pas de doute, on <\/em><em>\u00e9<\/em><em>tait au pays des l<\/em><em>\u00e9<\/em><em>muriens. Sur le d<\/em><em>\u00e9<\/em><em>cor du bar, un <\/em>maki* <em>rigolard entourait sa queue annel<\/em><em>\u00e9<\/em><em>e autour de l\u2019<\/em><em>\u00e9<\/em><em>norme capsule de coca-cola qui lui servait d\u2019aur<\/em><em>\u00e9<\/em><em>ole. Juste en dessous, un beau dos malgache, pench<\/em><em>\u00e9<\/em><em> sur le comptoir tendait avec humour un d<\/em><em>\u00e9<\/em><em>bardeur. Un maki \u2014encore un \u2014 avertissait d\u2019un <\/em><em>\u00ab&nbsp;<\/em>Vas-y m\u00f4lo Vazaha au pays du mora mora&nbsp;**<em>\u00bb<\/em><em> ceux qui n\u2019auraient pas encore compris qu\u2019on <\/em><em>\u00e9<\/em><em>tait dans un ailleurs. Je me suis approch<\/em><em>\u00e9<\/em><em>e d\u2019une extr<\/em><em>\u00e9<\/em><em>mit<\/em><em>\u00e9<\/em><em> du bar. La Vache qui rit, peinte sur le mur, riait et l<\/em><em>\u00e0<\/em><em> on savait pourquoi.<\/em><em>&nbsp;\u00bb<\/em><em><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maki&nbsp;: esp\u00e8ce de l\u00e9murien<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vazaha&nbsp;: nom donn\u00e9 par les Malgaches aux \u00e9trangers blancs qui ne sont pas n\u00e9s sur l\u2019\u00eele<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mora mora&nbsp;: tout doucement<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bribe 2<\/strong>&nbsp;Je suis sur le quai des Esclavons. Il y souffle une petite bise bien mordante.Le soleil de l\u2019apr\u00e8s-midi fait ses adieux \u2014 touchants, les adieux \u2014 au ciel gorge de pigeon qu\u2019irisent des pourpres et des bleus. Comme c\u2019est bien dit&nbsp;! Pour ne pas \u00eatre en reste, le globe de la Douane de mer ajoute sa touche d\u2019or. Tr\u00e8s fond de sc\u00e8ne pour un final d\u2019op\u00e9ra, cette opale pos\u00e9e sur une am\u00e9thyste. M\u00eame que le velours de la lagune, \u00e0 force d\u2019\u00eatre violet, finira bient\u00f4t noir&nbsp;!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bribe 3<\/strong><em>&nbsp;<\/em><em>F<\/em><em>\u00e9<\/em><em>lix de Br<\/em><em>\u00e8<\/em><em>des <\/em><em>\u00e9<\/em><em>tait rentr<\/em><em>\u00e9<\/em><em> fin juillet. En quittant le Vietnam, <\/em><em>\u00e0<\/em><em> soixante-cinq ans, il avait laiss<\/em><em>\u00e9<\/em><em> derri<\/em><em>\u00e8<\/em><em>re lui quarante ans de sa vie. Son entreprise d\u2019import-export en produits pharmaceutiques, ses partenaires de majong, ses conga<\/em><em>\u00ef<\/em><em>s, tous ses amis et surtout ses fleurs. C\u2019<\/em><em>\u00e9<\/em><em>tait un Fran<\/em><em>\u00e7<\/em><em>ais de l\u2019Indochine coloniale, celle de la bonne <\/em><em>\u00e9<\/em><em>poque. De haute taille, il habitait sa maigreur un peu vo<\/em><em>\u00fb<\/em><em>t<\/em><em>\u00e9<\/em><em>e avec nonchalance et gaiet<\/em><em>\u00e9<\/em><em>. Ses grandes jambes dess<\/em><em>\u00e9<\/em><em>ch<\/em><em>\u00e9<\/em><em>es presque toujours habill<\/em><em>\u00e9<\/em><em>es de shorts blancs et de chaussettes montantes. Un casque colonial sur son cr<\/em><em>\u00e2<\/em><em>ne nu, il mouvait son grand corps avec lenteur, comme pour s\u2019excuser de d<\/em><em>\u00e9<\/em><em>ranger l\u2019air qui l\u2019entourait. <\/em><em>\u00c0<\/em><em> ses yeux r<\/em><em>\u00ea<\/em><em>veurs, <\/em><em>\u00e0<\/em><em> sa lippe gourmande, on devinait qu\u2019il aimait le plaisir. Il parlait vietnamien avec douceur, ce qui ne manquait pas de surprendre car cette langue est plut<\/em><em>\u00f4<\/em><em>t hach<\/em><em>\u00e9<\/em><em>e. Son accent original l\u2019avait dot<\/em><em>\u00e9<\/em><em> d\u2019un charme ravageur.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;<\/strong><strong>Bribe 4<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>\u00ab&nbsp;<\/em>Moi c\u2019est Istvan, vous le savez d\u00e9j\u00e0. Istvan, c\u2019est Etienne, St\u00e9phane, si vous pr\u00e9f\u00e9rez et je suis hongrois. Enfin j\u2019\u00e9tais hongrois, maintenant je suis fran\u00e7ais, franco-am\u00e9ricain plus exactement. Je suis n\u00e9 en 1936. Beaucoup de gar\u00e7ons s\u2019appellent comme moi en Hongrie, \u00e0 cause d\u2019Etienne, notre premier roi. Pour nous les Magyars, notre premier roi, ce n\u2019est pas rien, c\u2019est tout&nbsp;! Je digresse, je digresse, je tourne autour du pot\u2026 Je ne vais tout de m\u00eame pas vous raconter l\u2019histoire de la Hongrie, n\u2019est-ce pas&nbsp;? Un peu plus de Tokay&nbsp;?<\/li>\n\n\n\n<li>Tout \u00e0 l\u2019heure. Je vous \u00e9coute.<\/li>\n\n\n\n<li>Oui, je suis n\u00e9 hongrois, \u00e0 Sopron, petite ville proche de la fronti\u00e8re autrichienne, dans la maison paysanne de ma famille maternelle. Mais c\u2019est \u00e0 Budapest que j\u2019ai \u00e9t\u00e9 \u00e9lev\u00e9 par mes parents, avec ma petite s\u0153ur Vera. Mon grand-p\u00e8re paternel \u00e9tait tourneur sur m\u00e9taux, mon p\u00e8re aussi dans sa jeunesse, mais surtout il \u00e9tait communiste. Nous \u00e9tions tous communistes. Plus ou moins, mais tous. Mon p\u00e8re, lui, faisait partie des \u00ab&nbsp;plus&nbsp;\u00bb. Il s\u2019\u00e9tait \u00e9puis\u00e9 les yeux, apr\u00e8s son travail, sur des livres de droit, pour gravir les \u00e9chelons de son usine, mais surtout ceux du Parti. En 1956, il ne faisait plus le tourneur, il appartenait \u00e0 la S\u00e9curit\u00e9. \u00c7a ne vous dit pas grand-chose, la S\u00e9curit\u00e9, qu\u2019importe. Mon p\u00e8re n\u2019\u00e9tait plus un prol\u00e9taire, il \u00e9tait un apparatchik du r\u00e9gime&nbsp;; c\u2019est pourquoi j\u2019avais une place \u00e0 l\u2019universit\u00e9. J\u2019\u00e9tudiais la m\u00e9decine, j\u2019avais vingt ans. Bon je fais court&nbsp;: en 1956 des \u00e9tudiants de Budapest, dont j\u2019\u00e9tais, se sont r\u00e9volt\u00e9s. La S\u00e9curit\u00e9 a tir\u00e9 sur les manifestants. Mon p\u00e8re \u00e9tait un tireur, moi j\u2019\u00e9tais un tir\u00e9&nbsp;! Tokay&nbsp;?&nbsp;\u00bb<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4 Nouvelles de mon chantier<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toujours pr\u00e9occup\u00e9e par la deuxi\u00e8me partie de mon roman en cours d\u2019\u00e9criture.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quelle forme lui donner\u00a0? Lettre, r\u00e9cit ou monologue int\u00e9rieur\u00a0?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je cherche aussi toujours le titre ce roman.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par contre, j\u2019ai une id\u00e9e tr\u00e8s nette de sa fin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5 Merci Nolwenn<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tout \u00e9crire&nbsp;? On voudrait bien, on en r\u00eave. On n\u2019ose pas toujours : trop cru, trop personnel, trop indiscret, blessant pour un tiers\u2026 Pourtant on sait bien que si on n\u2019a pas \u00e9crit avec son \u00e2me, son corps, ses tripes, son intuition, son imagination, on n\u2019a pas \u00e9crit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1 \u00ab&nbsp;Comment mourir sans \u00eatre n\u00e9&nbsp;?&nbsp;\u00bb 2 La chambre 12 C\u2019est dans un fauteuil roulant que je d\u00e9couvre la chambre 12 de la maison de sant\u00e9 dans laquelle je s\u00e9journerai plusieurs semaines pour ma convalescence et la r\u00e9\u00e9ducation de ma hanche droite. L\u2019aide-soignante ouvre la porte, me pousse en avant. D\u2019un regard circulaire, je d\u00e9couvre mon nouveau domaine&nbsp;: murs jaune, <a class=\"more-link\" href=\"https:\/\/www.tierslivre.net\/ateliers\/ete-2026-02-voyages\/\">Continuer la lecture<span class=\"screen-reader-text\">#chroniques #02 | Voyages<\/span><span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":670,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"footnotes":""},"categories":[8106,8147],"tags":[],"class_list":["post-215549","post","type-post","status-publish","format-standard","hentry","category-ete-2026-chroniques","category-ete-2026-02-semaine-2"],"_links":{"self":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts\/215549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/users\/670"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/comments?post=215549"}],"version-history":[{"count":5,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts\/215549\/revisions"}],"predecessor-version":[{"id":215608,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/posts\/215549\/revisions\/215608"}],"wp:attachment":[{"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/media?parent=215549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/categories?post=215549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tierslivre.net\/ateliers\/wp-json\/wp\/v2\/tags?post=215549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}